{"id":65887,"date":"2019-05-13T15:16:44","date_gmt":"2019-05-13T15:16:44","guid":{"rendered":"https:\/\/www.unitedabrasives.com\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/"},"modified":"2024-10-07T10:57:08","modified_gmt":"2024-10-07T10:57:08","slug":"disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite","status":"publish","type":"post","link":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/","title":{"rendered":"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9"},"content":{"rendered":"<div id=\"pl-40038\" class=\"panel-layout\">\n<div id=\"pg-40038-0\" class=\"panel-grid panel-no-style\" data-style=\"{\"background_image_attachment\":false,\"background_display\":\"tile\",\"cell_alignment\":\"flex-start\"}\" data-ratio=\"1\" data-ratio-direction=\"right\">\n<div id=\"pgc-40038-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-40038-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" data-style=\"{\"background_image_attachment\":false,\"background_display\":\"tile\"}\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p><img decoding=\"async\" class=\"aligncenter wp-image-40039 size-large\" src=\"https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize-828x1024.jpg\" alt=\"\" width=\"828\" height=\"1024\" srcset=\"https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize-243x300.jpg 243w, https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize-768x950.jpg 768w, https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize-828x1024.jpg 828w\" sizes=\"(max-width: 828px) 100vw, 828px\" \/>  Sur la plupart des chantiers de construction, les scies portatives \u00e0 gaz sont des outils essentiels.  <!--more-->Elles permettent \u00e0 l&rsquo;utilisateur d&rsquo;effectuer des coupes rapides sur une grande vari\u00e9t\u00e9 de mat\u00e9riaux, qu&rsquo;il s&rsquo;agisse de corni\u00e8res, d&rsquo;\u00e9tais, de barres d&rsquo;armature, de tabliers m\u00e9talliques, de b\u00e9ton ou d&rsquo;asphalte.<br \/>\nUne scie portative\/\u00e0 gaz peut \u00eatre un outil parfait &#8211; \u00e0 condition que l&rsquo;op\u00e9rateur utilise la meule appropri\u00e9e et la plus s\u00fbre pour le travail.<br \/>\nUnited Abrasives propose l&rsquo;une des gammes les plus compl\u00e8tes de meules de tron\u00e7onnage pour scies portatives\/\u00e0 gaz de l&rsquo;industrie.<br \/>\nNous avons huit formulations uniques qui couvrent une large gamme d&rsquo;applications.<br \/>\nEn outre, les meules de tron\u00e7onnage de United Abrasives sont fabriqu\u00e9es aux \u00c9tats-Unis et d\u00e9passent les normes ANSI en mati\u00e8re de s\u00e9curit\u00e9 !<br \/>\nAlors, que devez-vous savoir ?       <\/p>\n<h3><strong>Conseils de s\u00e9curit\u00e9<\/strong><\/h3>\n<p>  Quelques conseils utiles permettent toujours d&rsquo;utiliser avec succ\u00e8s et en toute s\u00e9curit\u00e9 une meule \u00e0 tron\u00e7onner.<br \/>\nLorsque vous utilisez nos meules, veillez \u00e0 toujours.. :   <\/p>\n<ul>\n<li>Utilisez des roues robustes sur les scies \u00e0 grande vitesse fonctionnant au gaz.<\/li>\n<li><strong>Toutes les roues ne sont pas \u00e9gales.<\/strong>  De nombreux meules de tron\u00e7onnage bon march\u00e9 sont fabriqu\u00e9es \u00e0 partir de mati\u00e8res premi\u00e8res de qualit\u00e9 inf\u00e9rieure qui risquent de ne pas fonctionner.<\/li>\n<li>Veillez \u00e0 utiliser la molette adapt\u00e9e au mat\u00e9riau que vous d\u00e9coupez.<\/li>\n<li>Lors du montage d&rsquo;une nouvelle roue, veillez \u00e0 ce que le fil de la bougie soit d\u00e9branch\u00e9 de la scie et \u00e0 ce que les brides appropri\u00e9es soient en place et en bon \u00e9tat.<\/li>\n<\/ul>\n<p>  Comme pour de nombreux produits abrasifs, une mauvaise utilisation d&rsquo;un disque \u00e0 tron\u00e7onner peut entra\u00eener sa rupture et des blessures.<br \/>\nDans cette optique, veillez \u00e0 :   <\/p>\n<ul>\n<li>Porter un \u00e9quipement de protection individuelle (EPI) appropri\u00e9<\/li>\n<li>Inspectez visuellement toutes les roues avant le montage pour v\u00e9rifier qu&rsquo;elles ne sont pas endommag\u00e9es.<\/li>\n<li>N&rsquo;utilisez jamais les lames de scie \u00e0 gaz avec de l&rsquo;eau ou des lubrifiants.<\/li>\n<li>Ne tenez JAMAIS le mat\u00e9riau \u00e0 couper dans votre main ou avec votre pied.<\/li>\n<li>Attendez l&rsquo;arr\u00eat complet de la roue avant de saisir les pi\u00e8ces coup\u00e9es.<\/li>\n<li>Le <a href=\"https:\/\/law.resource.org\/pub\/us\/cfr\/ibr\/002\/ansi.b7.1.1970.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">code de s\u00e9curit\u00e9 ANSI B7.1<\/a> d\u00e9finit des conditions d&rsquo;utilisation s\u00fbres pour toutes les meules de coupe et de meulage abrasives et <strong>doit \u00eatre <\/strong>respect\u00e9.<\/li>\n<li>Ne permettez JAMAIS aux op\u00e9rateurs d&rsquo;effectuer une coupe, puis de retirer la fraise de la coupe contre le c\u00f4t\u00e9 de la meule.<br \/>\nCes meules sont con\u00e7ues pour couper sur la p\u00e9riph\u00e9rie de la meule UNIQUEMENT !<br \/>\nLe meulage sur le c\u00f4t\u00e9 d&rsquo;une meule peut endommager le renfort int\u00e9rieur en fibre de verre, entra\u00eenant une rupture et des blessures potentielles.  <\/li>\n<li>Si vous utilisez une scie \u00e0 grande vitesse, veillez \u00e0 utiliser un disque \u00e0 tron\u00e7onner robuste.<\/li>\n<\/ul>\n<h3><strong>Quelle roue dois-je utiliser ?<br \/>\nTout d\u00e9pend du mat\u00e9riau et de l&rsquo;outil <\/strong><\/h3>\n<p>  Avec huit formulations uniques, United Abrasives dispose d&rsquo;un disque \u00e0 tron\u00e7onner portable\/scie \u00e0 gaz pour les mat\u00e9riaux les plus courants utilis\u00e9s sur un chantier.  <strong>Roues \u00e0 usage intensif : Con\u00e7ues avec des renforts plus importants pour une utilisation sur des scies \u00e0 grande vitesse.<\/strong><\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.unitedabrasives.com\/mmi-family\/a24r-4\/\" target=\"_blank\" rel=\"noopener noreferrer\">A24R<\/a>: <\/strong>Con\u00e7ue pour les professionnels, la meule en oxyde d&rsquo;aluminium A24R offre des performances constantes et une longue dur\u00e9e de vie.<br \/>\nCette lame est id\u00e9ale pour couper l&rsquo;acier de construction, les corni\u00e8res, les barres d&rsquo;armature et les tuyaux. <\/li>\n<li><strong><a href=\"https:\/\/www.unitedabrasives.com\/mmi-family\/xfc\/\" target=\"_blank\" rel=\"noopener noreferrer\">XFC\u2122<\/a>:<\/strong> Sp\u00e9cialement formul\u00e9 pour une coupe extr\u00eamement rapide sans grippage.<br \/>\nId\u00e9al pour couper une grande vari\u00e9t\u00e9 d&rsquo;acier de construction, de tuyaux, de corni\u00e8res et de barres d&rsquo;armature.<br \/>\nCoupe \u00e9galement l&rsquo;acier inoxydable et les alliages \u00e0 haute r\u00e9sistance \u00e0 la traction de mani\u00e8re efficace.  <\/li>\n<li><strong><a href=\"https:\/\/www.unitedabrasives.com\/mmi-family\/hobo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hobo\u00ae<\/a>:<\/strong> Cette roue est con\u00e7ue pour couper l&rsquo;acier des lignes principales, des embranchements secondaires, des structures lourdes et des barres.<br \/>\nCette lame est renforc\u00e9e par de la fibre de verre pour une s\u00e9curit\u00e9 maximale. <\/li>\n<li><strong><a href=\"https:\/\/www.unitedabrasives.com\/mmi-family\/brute\/\" target=\"_blank\" rel=\"noopener noreferrer\">Brute\u2122<\/a>: <\/strong>Con\u00e7ue pour couper les platelages m\u00e9talliques, les m\u00e9taux fins et les t\u00f4les.<br \/>\nLe liant extr\u00eamement dur et la fibre de verre unique permettent \u00e0 cette lame de couper dans les applications les plus exigeantes, l\u00e0 o\u00f9 les autres lames \u00e9chouent <\/li>\n<li><strong><a href=\"https:\/\/www.unitedabrasives.com\/mmi-family\/ductile\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ductile\u2122<\/a>: <\/strong>Utilisant une combinaison d&rsquo;oxyde d&rsquo;aluminium et de carbure de silicium, cette lame est id\u00e9ale pour couper les tuyaux ductiles (tuyaux en acier tr\u00e8s dur rev\u00eatus de ciment), les conduites d&rsquo;eau, la fonte et les m\u00e9taux extra-durs.<br \/>\nElle est \u00e9galement id\u00e9ale pour couper les tuyaux hydrauliques et les tuyaux en PVC. <\/li>\n<li><strong><a href=\"https:\/\/www.unitedabrasives.com\/mmi-family\/c24r-3\/\" target=\"_blank\" rel=\"noopener noreferrer\">C24R<\/a>: <\/strong>Con\u00e7ue pour couper la pierre, la brique, les agr\u00e9gats tendres, la ma\u00e7onnerie, le b\u00e9ton, les tuyaux schedule 40 et 80.<\/li>\n<li><strong><a href=\"https:\/\/www.unitedabrasives.com\/mmi-family\/big-m-a-c\/\" target=\"_blank\" rel=\"noopener noreferrer\">Big M.A.C.<\/a>\u2122 : <\/strong>Le grain sp\u00e9cial de carbure de silicium est id\u00e9al pour couper la <strong>ma\u00e7onnerie<\/strong>, l&rsquo;<strong>asphalte<\/strong>et le <strong>b\u00e9ton<\/strong>.<br \/>\nCette roue unique dure environ 40% plus longtemps que les roues \u00e0 b\u00e9ton \u00e0 usage g\u00e9n\u00e9ral <\/li>\n<\/ul>\n<p><strong>Roues standardSAIT<\/strong><strong><a href=\"https:\/\/www.unitedabrasives.com\/mmi-family\/sait-pro-metal\/\" target=\"_blank\" rel=\"noopener noreferrer\">Pro :<\/a> <\/strong>Con\u00e7ue pour la coupe rapide des m\u00e9taux ferreux.<br \/>\nNotre meilleur rapport qualit\u00e9-prix.   <\/p>\n<h3>Vous avez encore besoin d&rsquo;aide ?<\/h3>\n<p>  Si vous ne savez toujours pas quel produit convient \u00e0 votre travail, consultez la recherche d&rsquo;applications de produits mentionn\u00e9e ci-dessus<a href=\"https:\/\/www.unitedabrasives.com\/resources\/product-selection-tools\/find-product-for-your-application\/\" target=\"_blank\" rel=\"noopener noreferrer\">(cliquez ici pour y acc\u00e9der<\/a>), ou n&rsquo;h\u00e9sitez pas \u00e0 <a href=\"https:\/\/www.unitedabrasives.com\/contact-us\/\" target=\"_blank\" rel=\"noopener noreferrer\">nous contacter directement.<\/a> <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sur la plupart des chantiers de construction, les scies portatives \u00e0 gaz sont des outils essentiels.<\/p>\n","protected":false},"author":1,"featured_media":64059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[1791,1789,1787,1788,1790],"class_list":["post-65887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-decoupage","tag-meule-de-tronconnage-portable","tag-meules-a-tronconner","tag-roue-de-scie-a-gaz","tag-scie-a-gaz-portable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9 - United Abrasives<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9 - United Abrasives\" \/>\n<meta property=\"og:description\" content=\"Sur la plupart des chantiers de construction, les scies portatives \u00e0 gaz sont des outils essentiels.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/\" \/>\n<meta property=\"og:site_name\" content=\"United Abrasives\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-13T15:16:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-07T10:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize-828x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/#\\\/schema\\\/person\\\/6715d0ada8b68b3f617f3ee00c8f5cb1\"},\"headline\":\"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9\",\"datePublished\":\"2019-05-13T15:16:44+00:00\",\"dateModified\":\"2024-10-07T10:57:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/\"},\"wordCount\":916,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedabrasives.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize.jpg\",\"keywords\":[\"d\u00e9coupage\",\"meule de tron\u00e7onnage portable\",\"meules \u00e0 tron\u00e7onner\",\"roue de scie \u00e0 gaz\",\"scie \u00e0 gaz portable\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/\",\"url\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/\",\"name\":\"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9 - United Abrasives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedabrasives.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize.jpg\",\"datePublished\":\"2019-05-13T15:16:44+00:00\",\"dateModified\":\"2024-10-07T10:57:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/#\\\/schema\\\/person\\\/6715d0ada8b68b3f617f3ee00c8f5cb1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unitedabrasives.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unitedabrasives.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize.jpg\",\"width\":1941,\"height\":2400,\"caption\":\"Gas Saw Wheels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/\",\"name\":\"United Abrasives\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/#\\\/schema\\\/person\\\/6715d0ada8b68b3f617f3ee00c8f5cb1\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a77968d3aa3f1727e143677df269946d9d98911367f8b4b21bf1bcdc5718190?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a77968d3aa3f1727e143677df269946d9d98911367f8b4b21bf1bcdc5718190?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a77968d3aa3f1727e143677df269946d9d98911367f8b4b21bf1bcdc5718190?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.unitedabrasives.com\\\/fr\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9 - United Abrasives","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/","og_locale":"fr_FR","og_type":"article","og_title":"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9 - United Abrasives","og_description":"Sur la plupart des chantiers de construction, les scies portatives \u00e0 gaz sont des outils essentiels.","og_url":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/","og_site_name":"United Abrasives","article_published_time":"2019-05-13T15:16:44+00:00","article_modified_time":"2024-10-07T10:57:08+00:00","og_image":[{"width":828,"height":1024,"url":"https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize-828x1024.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/#article","isPartOf":{"@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/"},"author":{"name":"admin","@id":"https:\/\/www.unitedabrasives.com\/fr\/#\/schema\/person\/6715d0ada8b68b3f617f3ee00c8f5cb1"},"headline":"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9","datePublished":"2019-05-13T15:16:44+00:00","dateModified":"2024-10-07T10:57:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/"},"wordCount":916,"commentCount":0,"image":{"@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize.jpg","keywords":["d\u00e9coupage","meule de tron\u00e7onnage portable","meules \u00e0 tron\u00e7onner","roue de scie \u00e0 gaz","scie \u00e0 gaz portable"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/","url":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/","name":"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9 - United Abrasives","isPartOf":{"@id":"https:\/\/www.unitedabrasives.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/#primaryimage"},"image":{"@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize.jpg","datePublished":"2019-05-13T15:16:44+00:00","dateModified":"2024-10-07T10:57:08+00:00","author":{"@id":"https:\/\/www.unitedabrasives.com\/fr\/#\/schema\/person\/6715d0ada8b68b3f617f3ee00c8f5cb1"},"breadcrumb":{"@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/#primaryimage","url":"https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize.jpg","contentUrl":"https:\/\/www.unitedabrasives.com\/wp-content\/uploads\/2019\/05\/Gas-Saw-Action-Family_edit-StickersRemoved-smallersize.jpg","width":1941,"height":2400,"caption":"Gas Saw Wheels"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedabrasives.com\/fr\/blog\/disques-a-tronconner-pour-scies-portatives-tout-est-question-de-securite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedabrasives.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Disques \u00e0 tron\u00e7onner pour scies portatives : Tout est question de s\u00e9curit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedabrasives.com\/fr\/#website","url":"https:\/\/www.unitedabrasives.com\/fr\/","name":"United Abrasives","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedabrasives.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.unitedabrasives.com\/fr\/#\/schema\/person\/6715d0ada8b68b3f617f3ee00c8f5cb1","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9a77968d3aa3f1727e143677df269946d9d98911367f8b4b21bf1bcdc5718190?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9a77968d3aa3f1727e143677df269946d9d98911367f8b4b21bf1bcdc5718190?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a77968d3aa3f1727e143677df269946d9d98911367f8b4b21bf1bcdc5718190?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.unitedabrasives.com\/fr\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedabrasives.com\/fr\/wp-json\/wp\/v2\/posts\/65887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedabrasives.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unitedabrasives.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedabrasives.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedabrasives.com\/fr\/wp-json\/wp\/v2\/comments?post=65887"}],"version-history":[{"count":0,"href":"https:\/\/www.unitedabrasives.com\/fr\/wp-json\/wp\/v2\/posts\/65887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitedabrasives.com\/fr\/wp-json\/wp\/v2\/media\/64059"}],"wp:attachment":[{"href":"https:\/\/www.unitedabrasives.com\/fr\/wp-json\/wp\/v2\/media?parent=65887"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unitedabrasives.com\/fr\/wp-json\/wp\/v2\/tags?post=65887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}